{"id":8176,"date":"2021-06-09T07:28:07","date_gmt":"2021-06-09T07:28:07","guid":{"rendered":"https:\/\/penosil.com\/es\/?p=8176"},"modified":"2021-06-21T11:17:52","modified_gmt":"2021-06-21T11:17:52","slug":"pegar-y-construir-con-espuma-adhesiva","status":"publish","type":"post","link":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/","title":{"rendered":"Pegar y construir con espuma adhesiva"},"content":{"rendered":"\n<p><strong>Tradicionalmente se ha utilizado la espuma de poliuretano para pegar por su gran adherencia pero el inconveniente es que no pod\u00edamos controlar su gran capacidad de expansi\u00f3n. La expansi\u00f3n de la espuma adhesiva PENOSIL EasyPega es controlada y en este tutorial de Bricocrack se mostrar\u00e1 sobre qu\u00e9 materiales la puedes utilizar, qu\u00e9 pasa cuando los materiales que pegamos son m\u00e1s pesados y c\u00f3mo se debe aplicar para que funcione de manera eficaz.&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Pegar y construir con espuma adhesiva (Bricocrack)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dI-K3E6uyyM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Espuma adhesiva con el exclusivo aplicador EasyGun para la fijaci\u00f3n de una amplia variedad de materiales de construcci\u00f3n.<\/strong><\/p>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>MULTIMATERIAL<\/strong><\/h5>\n\n\n\n<p>La espuma adhesiva EasyPega Todos los trabajos tiene excelentes propiedades adherentes en la mayor\u00eda de los materiales utilizados com\u00fanmente en la construcci\u00f3n, tanto en interiores como en exteriores.<br>Posee una excelente adhesi\u00f3n sin imprimaci\u00f3n previa en la mayor\u00eda de los materiales, como hormig\u00f3n, ladrillos, piedra, yeso, madera, metales, poliestireno, PVC y otros pl\u00e1sticos, as\u00ed como a sustratos minerales.<\/p>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>PEGADO EN<\/strong>&nbsp;<strong>60<\/strong>&nbsp;<strong>SEGUNDOS<\/strong><\/h5>\n\n\n\n<p>La f\u00f3rmula de EasyPega proporciona una fijaci\u00f3n r\u00e1pida y fuerte.<br>La espuma adhesiva es uniforme y el\u00e1stica, lo que permite repartir y absorber las tensiones uniformemente.<\/p>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>RENDIMIENTO 45 METROS LINEALES<\/strong><\/h5>\n\n\n\n<p>EasyPega Todos los trabajos se presenta listo para su uso, sin mezcla previa. Sustituye en muchos casos la fijaci\u00f3n mec\u00e1nica con tornillos o la tradicional a base de mezcla de productos \u00e1ridos, siendo una soluci\u00f3n simple, r\u00e1pida, limpia, y econ\u00f3mica.<\/p>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>PARA CONSTRUCCI\u00d3N DE MUROS<\/strong><\/h5>\n\n\n\n<p>Se puede utilizar para la uni\u00f3n y fijaci\u00f3n de bloques ligeros en la construcci\u00f3n de tabiques interiores que no soporten cargas. La primera fila de bloques debe estar bien nivelada. Adem\u00e1s, la espuma proporciona un excelente aislamiento t\u00e9rmico y es una buena barrera ac\u00fastica contra el ruido.<\/p>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>PANELES PARA REVESTIR PAREDES<\/strong><\/h5>\n\n\n\n<p>La espuma adhesiva es ideal para la fijaci\u00f3n de placas de yeso, paneles de aislamiento, alf\u00e9izares de ventanas y paneles de acabado interior. Aprobado para sistemas de ETICS. La fijaci\u00f3n de estos materiales no precisa trabajos adicionales.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/penosil.com\/es\/producto\/easypega-todos-los-trabajos\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre.png\" alt=\"\" class=\"wp-image-8177\" width=\"543\" height=\"174\" srcset=\"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre.png 532w, https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre-250x80.png 250w, https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre-120x38.png 120w, https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre-180x58.png 180w, https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Sans-titre-300x96.png 300w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"Tradicionalmente se ha utilizado la espuma de poliuretano para pegar por su gran adherencia pero el inconveniente es que no pod\u00edamos controlar su gran capacidad de expansi\u00f3n. La expansi\u00f3n de la espuma adhesiva PENOSIL EasyPega es controlada y en este tutorial de Bricocrack se mostrar\u00e1 sobre qu\u00e9 materiales la puedes utilizar, qu\u00e9 pasa cuando los [&hellip;]","protected":false},"author":24,"featured_media":8164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-8176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pegar y construir con espuma adhesiva - Penosil Spain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pegar y construir con espuma adhesiva - Penosil Spain\" \/>\n<meta property=\"og:description\" content=\"Tradicionalmente se ha utilizado la espuma de poliuretano para pegar por su gran adherencia pero el inconveniente es que no pod\u00edamos controlar su gran capacidad de expansi\u00f3n. La expansi\u00f3n de la espuma adhesiva PENOSIL EasyPega es controlada y en este tutorial de Bricocrack se mostrar\u00e1 sobre qu\u00e9 materiales la puedes utilizar, qu\u00e9 pasa cuando los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Penosil Spain\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T07:28:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-21T11:17:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"armand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"armand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/\"},\"author\":{\"name\":\"armand\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/#\\\/schema\\\/person\\\/788772dcbc57a15a5c601c2a4c9b14c4\"},\"headline\":\"Pegar y construir con espuma adhesiva\",\"datePublished\":\"2021-06-09T07:28:07+00:00\",\"dateModified\":\"2021-06-21T11:17:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/\"},\"wordCount\":365,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/penosil.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/06\\\/Capture-decran-2021-06-08-a-10.29.21.png\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/\",\"url\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/\",\"name\":\"Pegar y construir con espuma adhesiva - Penosil Spain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/penosil.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/06\\\/Capture-decran-2021-06-08-a-10.29.21.png\",\"datePublished\":\"2021-06-09T07:28:07+00:00\",\"dateModified\":\"2021-06-21T11:17:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/#\\\/schema\\\/person\\\/788772dcbc57a15a5c601c2a4c9b14c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/penosil.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/06\\\/Capture-decran-2021-06-08-a-10.29.21.png\",\"contentUrl\":\"https:\\\/\\\/penosil.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/06\\\/Capture-decran-2021-06-08-a-10.29.21.png\",\"width\":2560,\"height\":1362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/pegar-y-construir-con-espuma-adhesiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/penosil.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pegar y construir con espuma adhesiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/penosil.com\\\/es\\\/\",\"name\":\"Penosil Spain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/penosil.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/penosil.com\\\/es\\\/#\\\/schema\\\/person\\\/788772dcbc57a15a5c601c2a4c9b14c4\",\"name\":\"armand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g\",\"caption\":\"armand\"},\"url\":\"https:\\\/\\\/penosil.com\\\/es\\\/author\\\/armand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pegar y construir con espuma adhesiva - Penosil Spain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/","og_locale":"es_ES","og_type":"article","og_title":"Pegar y construir con espuma adhesiva - Penosil Spain","og_description":"Tradicionalmente se ha utilizado la espuma de poliuretano para pegar por su gran adherencia pero el inconveniente es que no pod\u00edamos controlar su gran capacidad de expansi\u00f3n. La expansi\u00f3n de la espuma adhesiva PENOSIL EasyPega es controlada y en este tutorial de Bricocrack se mostrar\u00e1 sobre qu\u00e9 materiales la puedes utilizar, qu\u00e9 pasa cuando los [&hellip;]","og_url":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/","og_site_name":"Penosil Spain","article_published_time":"2021-06-09T07:28:07+00:00","article_modified_time":"2021-06-21T11:17:52+00:00","og_image":[{"width":2560,"height":1362,"url":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png","type":"image\/png"}],"author":"armand","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"armand","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#article","isPartOf":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/"},"author":{"name":"armand","@id":"https:\/\/penosil.com\/es\/#\/schema\/person\/788772dcbc57a15a5c601c2a4c9b14c4"},"headline":"Pegar y construir con espuma adhesiva","datePublished":"2021-06-09T07:28:07+00:00","dateModified":"2021-06-21T11:17:52+00:00","mainEntityOfPage":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/"},"wordCount":365,"commentCount":0,"image":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#primaryimage"},"thumbnailUrl":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/","url":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/","name":"Pegar y construir con espuma adhesiva - Penosil Spain","isPartOf":{"@id":"https:\/\/penosil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#primaryimage"},"image":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#primaryimage"},"thumbnailUrl":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png","datePublished":"2021-06-09T07:28:07+00:00","dateModified":"2021-06-21T11:17:52+00:00","author":{"@id":"https:\/\/penosil.com\/es\/#\/schema\/person\/788772dcbc57a15a5c601c2a4c9b14c4"},"breadcrumb":{"@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#primaryimage","url":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png","contentUrl":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21.png","width":2560,"height":1362},{"@type":"BreadcrumbList","@id":"https:\/\/penosil.com\/es\/pegar-y-construir-con-espuma-adhesiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/penosil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pegar y construir con espuma adhesiva"}]},{"@type":"WebSite","@id":"https:\/\/penosil.com\/es\/#website","url":"https:\/\/penosil.com\/es\/","name":"Penosil Spain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/penosil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/penosil.com\/es\/#\/schema\/person\/788772dcbc57a15a5c601c2a4c9b14c4","name":"armand","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb6be887a327ebb5ded30e91f01cefe88be7d45306270a58357645fa0bb095f0?s=96&d=mm&r=g","caption":"armand"},"url":"https:\/\/penosil.com\/es\/author\/armand\/"}]}},"author_meta":{"display_name":"armand","author_link":"https:\/\/penosil.com\/es\/author\/armand\/"},"featured_img":"https:\/\/penosil.com\/es\/wp-content\/uploads\/sites\/9\/2021\/06\/Capture-decran-2021-06-08-a-10.29.21-250x133.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/penosil.com\/es\/categor\u00eda\/sin-categorizar\/\" class=\"advgb-post-tax-term\">Sin categorizar<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Sin categorizar<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 5 a\u00f1os hace","modified":"Actualizado 5 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 06\/09\/2021","modified":"Actualizado el 06\/21\/2021"},"absolute_dates_time":{"created":"Publicado el 06\/09\/2021 7:28 am","modified":"Actualizado el 06\/21\/2021 11:17 am"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/posts\/8176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/comments?post=8176"}],"version-history":[{"count":4,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/posts\/8176\/revisions"}],"predecessor-version":[{"id":8252,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/posts\/8176\/revisions\/8252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/media\/8164"}],"wp:attachment":[{"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/media?parent=8176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/categories?post=8176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/penosil.com\/es\/wp-json\/wp\/v2\/tags?post=8176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}